{"id":6702,"date":"2022-10-14T09:12:35","date_gmt":"2022-10-14T09:12:35","guid":{"rendered":"https:\/\/www.anresis.ch\/?post_type=microorganisms&#038;p=6702"},"modified":"2025-03-04T14:02:18","modified_gmt":"2025-03-04T14:02:18","slug":"pollo","status":"publish","type":"microorganisms","link":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/","title":{"rendered":"Pollo"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Monitoraggio della resistenza nei polli<\/h2>\n<p>I grafici seguenti riassumono gli andamenti delle resistenze in campioni prelevati nei macelli (indicatore di resistenza negli effettivi di animali svizzeri) e nel commercio al dettaglio (indicatore di contaminazione della carne fresca). I dati raccolti dal 2006 mostrano un quadro diversificato: la resistenza \u00e8 aumentata significativamente in alcuni batteri, ma \u00e8 rimasta stabile o \u00e8 diminuita in altri.<\/p>\n<\/p>\n<div class=\"ig-section\">\n<div class=\"wrapper\">\n<div class=\"holder\">\n<div class=\"ig-graphic-layout-single\">\n<div class=\"ig-item block-article graphic-placement-below graphic-size-fullwidth graphic-layout-single\">\n<div class=\"row\">\n<div class=\"ig-mobile-button-holder\">\n\t\t\t\t\t\t\t\t\t<a class=\"button\" href=\"https:\/\/www.anresis.ch\/interactive-graphic.php?src=https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetlsrt\/?animal=Chicken\" target=\"_blank\">Grafico interattivo<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-embed-col media-wrap\">\n<div class=\"ig-embed\">\n\t\t\t\t\t\t\t\t\t\t<iframe loading=\"lazy\" width=\"\" height=\"1350\" src=\"https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetlsrt\/?animal=Chicken\"><\/iframe>\n\t\t\t\t\t\t\t\t\t<\/div>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"ig full-screen\" data-fancybox data-src=\"#ig-popup-790\" href=\"javascript:;\"><span class=\"icon icon-full\"><\/span><span>Additional Information<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div style=\"display: none;\" class=\"ig-popup\" id=\"ig-popup-790\">\n<div class=\"wrap\">\n<div class=\"ig-popup-content ig-popup-col-accordion\">\n<div class=\"ig-content-col txt-wrap\"><\/div>\n<div class=\"ig-accordion accordion\" id=\"accordion\">\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Come utilizzare il grafico interattivo<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>Selezionate un agente patogeno di interesse dai menu a tendina. Utilizzate le caselle di controllo per attivare o disattivare le classi di antibiotici, gli intervalli di confidenza o il tipo di grafico (percentuale o valori assoluti). Quando il mouse viene spostato sul grafico viene visualizzata una barra degli strumenti, che consente lo zoom o di mostrare i dati al passaggio del mouse.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Abbreviazioni<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>95% CI: intervallo di confidenza al 95%.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Struttura ed elaborazione dei dati<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>Per questa analisi sono stati utilizzati tutti gli isolati testati contro l\u2019agente patogeno corrispondente. I risultati sono riportati cos\u00ec come sono stati trasmessi dal Centro per le zoonosi, le malattie animali di origine batterica e la resistenza agli antibiotici (ZOBA).<\/p>\n<p>I dati sono forniti a fini di sorveglianza e non devono essere utilizzati esclusivamente per decisioni terapeutiche.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-popup-col-embed\">\n\t\t\t\t\t\t\t\t\t\t\t<iframe loading=\"lazy\" width=\"\" height=\"1350\" src=\"https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetlsrt\/?animal=Chicken\"><\/iframe>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-graphic-layout-single\">\n<div class=\"ig-item block-article graphic-placement-below graphic-size-fullwidth graphic-layout-single\">\n<div class=\"row\">\n<div class=\"ig-mobile-button-holder\">\n\t\t\t\t\t\t\t\t\t<a class=\"button\" href=\"https:\/\/www.anresis.ch\/interactive-graphic.php?src=https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetoverview\/?animal=Chicken\" target=\"_blank\">Grafico interattivo<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-embed-col media-wrap\">\n<div class=\"ig-embed\">\n\t\t\t\t\t\t\t\t\t\t<iframe loading=\"lazy\" width=\"\" height=\"825\" src=\"https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetoverview\/?animal=Chicken\"><\/iframe>\n\t\t\t\t\t\t\t\t\t<\/div>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"ig full-screen\" data-fancybox data-src=\"#ig-popup-719\" href=\"javascript:;\"><span class=\"icon icon-full\"><\/span><span>Additional Information<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div style=\"display: none;\" class=\"ig-popup\" id=\"ig-popup-719\">\n<div class=\"wrap\">\n<div class=\"ig-popup-content ig-popup-col-accordion\">\n<div class=\"ig-content-col txt-wrap\"><\/div>\n<div class=\"ig-accordion accordion\" id=\"accordion\">\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Come utilizzare il grafico interattivo<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>Utilizzate le caselle di controllo per attivare o disattivare i patogeni di interesse, la provenienza dei campioni o gli intervalli di confidenza. Quando il mouse viene spostato sul grafico viene visualizzata una barra degli strumenti, che consente lo zoom o di mostrare i dati al passaggio del mouse.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Abbreviazioni<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>95% CI: intervallo di confidenza al 95%.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-accordion-item\">\n<div class=\"ig-accordion-item-head\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"opener\">Struttura ed elaborazione dei dati<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<div class=\"ig-accordion-item-content slide\">\n<p>Per questa analisi sono stati utilizzati tutti gli isolati testati contro l\u2019agente patogeno corrispondente. I risultati sono riportati cos\u00ec come sono stati trasmessi dal Centro per le zoonosi, le malattie animali di origine batterica e la resistenza agli antibiotici (ZOBA).<\/p>\n<p>I dati sono forniti a fini di sorveglianza e non devono essere utilizzati esclusivamente per decisioni terapeutiche.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"ig-popup-col-embed\">\n\t\t\t\t\t\t\t\t\t\t\t<iframe loading=\"lazy\" width=\"\" height=\"825\" src=\"https:\/\/www.anresis.ch\/shinyapps\/Resistance\/VET\/vetoverview\/?animal=Chicken\"><\/iframe>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div><\/p>\n","protected":false},"featured_media":6535,"parent":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-6702","microorganisms","type-microorganisms","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pollo - ANRESIS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pollo - ANRESIS\" \/>\n<meta property=\"og:description\" content=\"Monitoraggio della resistenza nei polli I grafici seguenti riassumono gli andamenti delle resistenze in campioni prelevati nei macelli (indicatore di resistenza negli effettivi di animali svizzeri) e nel commercio al dettaglio (indicatore di contaminazione della carne fresca). I dati raccolti dal 2006 mostrano un quadro diversificato: la resistenza \u00e8 aumentata significativamente in alcuni batteri, ma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/\" \/>\n<meta property=\"og:site_name\" content=\"ANRESIS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T14:02:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/\",\"url\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/\",\"name\":\"Pollo - ANRESIS\",\"isPartOf\":{\"@id\":\"https:\/\/www.anresis.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg\",\"datePublished\":\"2022-10-14T09:12:35+00:00\",\"dateModified\":\"2025-03-04T14:02:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage\",\"url\":\"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg\",\"contentUrl\":\"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.anresis.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pollo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.anresis.ch\/#website\",\"url\":\"https:\/\/www.anresis.ch\/\",\"name\":\"ANRESIS\",\"description\":\"Swiss Centre for Antibiotic Resistance\",\"publisher\":{\"@id\":\"https:\/\/www.anresis.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.anresis.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.anresis.ch\/#organization\",\"name\":\"ANRESIS\",\"url\":\"https:\/\/www.anresis.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.anresis.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.anresis.ch\/wp-content\/uploads\/2019\/12\/anresis_logo.svg\",\"contentUrl\":\"https:\/\/www.anresis.ch\/wp-content\/uploads\/2019\/12\/anresis_logo.svg\",\"caption\":\"ANRESIS\"},\"image\":{\"@id\":\"https:\/\/www.anresis.ch\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pollo - ANRESIS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/","og_locale":"it_IT","og_type":"article","og_title":"Pollo - ANRESIS","og_description":"Monitoraggio della resistenza nei polli I grafici seguenti riassumono gli andamenti delle resistenze in campioni prelevati nei macelli (indicatore di resistenza negli effettivi di animali svizzeri) e nel commercio al dettaglio (indicatore di contaminazione della carne fresca). I dati raccolti dal 2006 mostrano un quadro diversificato: la resistenza \u00e8 aumentata significativamente in alcuni batteri, ma [&hellip;]","og_url":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/","og_site_name":"ANRESIS","article_modified_time":"2025-03-04T14:02:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/","url":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/","name":"Pollo - ANRESIS","isPartOf":{"@id":"https:\/\/www.anresis.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage"},"image":{"@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg","datePublished":"2022-10-14T09:12:35+00:00","dateModified":"2025-03-04T14:02:18+00:00","breadcrumb":{"@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#primaryimage","url":"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg","contentUrl":"https:\/\/www.anresis.ch\/wp-content\/uploads\/2022\/09\/chicken.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.anresis.ch\/it\/microorganisms\/pollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.anresis.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Pollo"}]},{"@type":"WebSite","@id":"https:\/\/www.anresis.ch\/#website","url":"https:\/\/www.anresis.ch\/","name":"ANRESIS","description":"Swiss Centre for Antibiotic Resistance","publisher":{"@id":"https:\/\/www.anresis.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.anresis.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.anresis.ch\/#organization","name":"ANRESIS","url":"https:\/\/www.anresis.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.anresis.ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.anresis.ch\/wp-content\/uploads\/2019\/12\/anresis_logo.svg","contentUrl":"https:\/\/www.anresis.ch\/wp-content\/uploads\/2019\/12\/anresis_logo.svg","caption":"ANRESIS"},"image":{"@id":"https:\/\/www.anresis.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.anresis.ch\/it\/wp-json\/wp\/v2\/microorganisms\/6702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.anresis.ch\/it\/wp-json\/wp\/v2\/microorganisms"}],"about":[{"href":"https:\/\/www.anresis.ch\/it\/wp-json\/wp\/v2\/types\/microorganisms"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.anresis.ch\/it\/wp-json\/wp\/v2\/media\/6535"}],"wp:attachment":[{"href":"https:\/\/www.anresis.ch\/it\/wp-json\/wp\/v2\/media?parent=6702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}